{"id":169,"date":"2016-08-24T15:53:39","date_gmt":"2016-08-24T18:53:39","guid":{"rendered":"http:\/\/blog.easylux.com.br\/sp\/?p=169"},"modified":"2017-07-12T18:15:06","modified_gmt":"2017-07-12T21:15:06","slug":"evolution-takes-time","status":"publish","type":"post","link":"https:\/\/blog.easylux.com.br\/sp\/evolution-takes-time\/","title":{"rendered":"Evolution takes time&#8230;"},"content":{"rendered":"<div style=\"display: none\" id=\"thumbnail\">\n<img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-229\" src=\"https:\/\/blog.easylux.com.br\/sp\/wp-content\/uploads\/2016\/08\/DINO1.png Array\" alt=\"REFLECTO\" width=\"25\" height=\"25\"\/>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-171\" src=\"https:\/\/blog.easylux.com.br\/sp\/wp-content\/uploads\/2016\/08\/evolution-1070x548.png\" alt=\"Retroreflectometer Evolution\" width=\"640\" height=\"328\" srcset=\"https:\/\/blog.easylux.com.br\/sp\/wp-content\/uploads\/2016\/08\/evolution-1070x548.png 1070w, https:\/\/blog.easylux.com.br\/sp\/wp-content\/uploads\/2016\/08\/evolution-470x241.png 470w, https:\/\/blog.easylux.com.br\/sp\/wp-content\/uploads\/2016\/08\/evolution-768x393.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":170,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blog.easylux.com.br\/sp\/wp-json\/wp\/v2\/posts\/169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.easylux.com.br\/sp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.easylux.com.br\/sp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.easylux.com.br\/sp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.easylux.com.br\/sp\/wp-json\/wp\/v2\/comments?post=169"}],"version-history":[{"count":3,"href":"https:\/\/blog.easylux.com.br\/sp\/wp-json\/wp\/v2\/posts\/169\/revisions"}],"predecessor-version":[{"id":309,"href":"https:\/\/blog.easylux.com.br\/sp\/wp-json\/wp\/v2\/posts\/169\/revisions\/309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.easylux.com.br\/sp\/wp-json\/wp\/v2\/media\/170"}],"wp:attachment":[{"href":"https:\/\/blog.easylux.com.br\/sp\/wp-json\/wp\/v2\/media?parent=169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.easylux.com.br\/sp\/wp-json\/wp\/v2\/categories?post=169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.easylux.com.br\/sp\/wp-json\/wp\/v2\/tags?post=169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}